{"id":18202,"date":"2023-12-18T03:30:36","date_gmt":"2023-12-18T03:30:36","guid":{"rendered":"https:\/\/plate2000.com\/product\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/"},"modified":"2024-04-30T03:35:05","modified_gmt":"2024-04-30T03:35:05","slug":"tr618500prp-6-x-18-x-0500-plastic-finish-blade","status":"publish","type":"product","link":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/","title":{"rendered":"TR618500PRP 6&#8243; X 18&#8243; X 0,500&#8243;"},"content":{"rendered":"<p>La gamme Plastic Pro est sp\u00e9cialement con\u00e7ue pour r\u00e9pondre aux besoins des finisseurs qui travaillent avec du b\u00e9ton color\u00e9 et r\u00e9pond au probl\u00e8me courant des marques de brunissage. Gr\u00e2ce \u00e0 leur conception innovante, ces lames offrent une performance sans faille et adaptable, garantissant la pr\u00e9vention de la casse et la stabilit\u00e9 n\u00e9cessaire pour obtenir une finition parfaite. Gr\u00e2ce \u00e0 leur conception innovante, ces lames offrent des performances continues et adaptables, garantissant la pr\u00e9vention des ruptures et la stabilit\u00e9 n\u00e9cessaire pour obtenir une finition impeccable. La ligne Plastic Pro, avec ses deux \u00e9paisseurs et sa construction en plastique \u00e0 haute r\u00e9sistance, garantit une plus longue dur\u00e9e de vie possible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une \u00e9paisseur de 0,500&#8221; qui permet non seulement de prolonger la dur\u00e9e de vie du cycle de levage, mais aussi d&#8217;am\u00e9liorer sa durabilit\u00e9. Fabriqu\u00e9 en plastique ph\u00e9nolique renforc\u00e9. \u00c9limine le risque de laisser des traces sombres de brunissage. Permet une finition pr\u00e9cise au plus pr\u00e8s des murs. Procure une finition lisse. Peut \u00eatre utilis\u00e9 sur une machine autoport\u00e9e seulement. Toutes les lames sont vendues par bo\u00eete de 4 unit\u00e9s. 100 bo\u00eetes par palette.<\/p>\n","protected":false},"featured_media":18073,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[103,101,117],"product_tag":[],"class_list":["post-18202","product","type-product","status-publish","has-post-thumbnail","product_cat-plastique-pro","product_cat-lames-de-truelles","product_cat-finition-plastique-pro","first","instock","shipping-taxable","product-type-simple"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"D\u00e9couvrez notre lame de truelle Plastique-Pro avec une taille de 6&quot;x18&quot;x0.500&quot; pour une performance optimale lors du lissage du b\u00e9ton.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Plate 2000 (P2K)\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Lame de truelle de finition en plastique 6&quot;x18&quot;x0.500&quot;\" \/>\n\t\t<meta property=\"og:description\" content=\"D\u00e9couvrez notre lame de truelle Plastique-Pro avec une taille de 6&quot;x18&quot;x0.500&quot; pour une performance optimale lors du lissage du b\u00e9ton.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/TR618500PRP.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/TR618500PRP.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-12-18T03:30:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-30T03:35:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/plate2000\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Lame de truelle de finition en plastique 6&quot;x18&quot;x0.500&quot;\" \/>\n\t\t<meta name=\"twitter:description\" content=\"D\u00e9couvrez notre lame de truelle Plastique-Pro avec une taille de 6&quot;x18&quot;x0.500&quot; pour une performance optimale lors du lissage du b\u00e9ton.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/TR618500PRP.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete-products\\\/#listItem\",\"name\":\"Produits b\\u00e9ton\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete-products\\\/#listItem\",\"position\":2,\"name\":\"Produits b\\u00e9ton\",\"item\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete-products\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/lames-de-truelles\\\/#listItem\",\"name\":\"Lames de truelles\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/lames-de-truelles\\\/#listItem\",\"position\":3,\"name\":\"Lames de truelles\",\"item\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/lames-de-truelles\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/lames-de-truelles\\\/plastique-pro\\\/#listItem\",\"name\":\"Plastique Pro \\u2013 0.375 I 0.500\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete-products\\\/#listItem\",\"name\":\"Produits b\\u00e9ton\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/lames-de-truelles\\\/plastique-pro\\\/#listItem\",\"position\":4,\"name\":\"Plastique Pro \\u2013 0.375 I 0.500\",\"item\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/lames-de-truelles\\\/plastique-pro\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/#listItem\",\"name\":\"Finition\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/lames-de-truelles\\\/#listItem\",\"name\":\"Lames de truelles\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/#listItem\",\"position\":5,\"name\":\"Finition\",\"item\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\\\/#listItem\",\"name\":\"TR618500PRP 6&#8243; X 18&#8243; X 0,500&#8243;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/lames-de-truelles\\\/plastique-pro\\\/#listItem\",\"name\":\"Plastique Pro \\u2013 0.375 I 0.500\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\\\/#listItem\",\"position\":6,\"name\":\"TR618500PRP 6&#8243; X 18&#8243; X 0,500&#8243;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/#listItem\",\"name\":\"Finition\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/#organization\",\"name\":\"Plate 2000 (P2K)\",\"description\":\"Manufacturer of concrete finishing products with a proven track record for quality and a focus on innovation.\",\"url\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/\",\"telephone\":\"+18778850085\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/plate2000.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/P2K_logo_rvb_noir.png\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\\\/#organizationLogo\",\"width\":976,\"height\":507,\"caption\":\"Black and red logo with letters P2K on gray background\"},\"image\":{\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/plate2000\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\\\/#webpage\",\"url\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\\\/\",\"name\":\"Lame de truelle de finition en plastique 6\\\"x18\\\"x0.500\\\"\",\"description\":\"D\\u00e9couvrez notre lame de truelle Plastique-Pro avec une taille de 6\\\"x18\\\"x0.500\\\" pour une performance optimale lors du lissage du b\\u00e9ton.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/plate2000.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/TR618500PRP.jpg\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\\\/#mainImage\",\"width\":2000,\"height\":2000},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/lames-de-truelles\\\/plastique-pro\\\/finition-plastique-pro\\\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\\\/#mainImage\"},\"datePublished\":\"2023-12-18T03:30:36+00:00\",\"dateModified\":\"2024-04-30T03:35:05+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/\",\"name\":\"Plate 2000 (P2K)\",\"description\":\"Manufacturer of concrete finishing products with a proven track record for quality and a focus on innovation.\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Lame de truelle de finition en plastique 6&quot;x18&quot;x0.500&quot;<\/title>\n\n","aioseo_head_json":{"title":"Lame de truelle de finition en plastique 6\"x18\"x0.500\"","description":"D\u00e9couvrez notre lame de truelle Plastique-Pro avec une taille de 6\"x18\"x0.500\" pour une performance optimale lors du lissage du b\u00e9ton.","canonical_url":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/plate2000.com\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete-products\/#listItem","name":"Produits b\u00e9ton"}},{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete-products\/#listItem","position":2,"name":"Produits b\u00e9ton","item":"https:\/\/plate2000.com\/fr\/concrete-products\/","nextItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/#listItem","name":"Lames de truelles"},"previousItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/#listItem","position":3,"name":"Lames de truelles","item":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/","nextItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/plastique-pro\/#listItem","name":"Plastique Pro \u2013 0.375 I 0.500"},"previousItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete-products\/#listItem","name":"Produits b\u00e9ton"}},{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/plastique-pro\/#listItem","position":4,"name":"Plastique Pro \u2013 0.375 I 0.500","item":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/plastique-pro\/","nextItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/#listItem","name":"Finition"},"previousItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/#listItem","name":"Lames de truelles"}},{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/#listItem","position":5,"name":"Finition","item":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/","nextItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/#listItem","name":"TR618500PRP 6&#8243; X 18&#8243; X 0,500&#8243;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/plastique-pro\/#listItem","name":"Plastique Pro \u2013 0.375 I 0.500"}},{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/#listItem","position":6,"name":"TR618500PRP 6&#8243; X 18&#8243; X 0,500&#8243;","previousItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/#listItem","name":"Finition"}}]},{"@type":"Organization","@id":"https:\/\/plate2000.com\/fr\/#organization","name":"Plate 2000 (P2K)","description":"Manufacturer of concrete finishing products with a proven track record for quality and a focus on innovation.","url":"https:\/\/plate2000.com\/fr\/","telephone":"+18778850085","logo":{"@type":"ImageObject","url":"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/P2K_logo_rvb_noir.png","@id":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/#organizationLogo","width":976,"height":507,"caption":"Black and red logo with letters P2K on gray background"},"image":{"@id":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/plate2000"]},{"@type":"WebPage","@id":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/#webpage","url":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/","name":"Lame de truelle de finition en plastique 6\"x18\"x0.500\"","description":"D\u00e9couvrez notre lame de truelle Plastique-Pro avec une taille de 6\"x18\"x0.500\" pour une performance optimale lors du lissage du b\u00e9ton.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/plate2000.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/TR618500PRP.jpg","@id":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/#mainImage","width":2000,"height":2000},"primaryImageOfPage":{"@id":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/#mainImage"},"datePublished":"2023-12-18T03:30:36+00:00","dateModified":"2024-04-30T03:35:05+00:00"},{"@type":"WebSite","@id":"https:\/\/plate2000.com\/fr\/#website","url":"https:\/\/plate2000.com\/fr\/","name":"Plate 2000 (P2K)","description":"Manufacturer of concrete finishing products with a proven track record for quality and a focus on innovation.","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/plate2000.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Plate 2000 (P2K)","og:type":"article","og:title":"Lame de truelle de finition en plastique 6&quot;x18&quot;x0.500&quot;","og:description":"D\u00e9couvrez notre lame de truelle Plastique-Pro avec une taille de 6&quot;x18&quot;x0.500&quot; pour une performance optimale lors du lissage du b\u00e9ton.","og:url":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/","og:image":"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/TR618500PRP.jpg","og:image:secure_url":"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/TR618500PRP.jpg","og:image:width":2000,"og:image:height":2000,"article:published_time":"2023-12-18T03:30:36+00:00","article:modified_time":"2024-04-30T03:35:05+00:00","article:publisher":"https:\/\/www.facebook.com\/plate2000","twitter:card":"summary_large_image","twitter:title":"Lame de truelle de finition en plastique 6&quot;x18&quot;x0.500&quot;","twitter:description":"D\u00e9couvrez notre lame de truelle Plastique-Pro avec une taille de 6&quot;x18&quot;x0.500&quot; pour une performance optimale lors du lissage du b\u00e9ton.","twitter:image":"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/TR618500PRP.jpg","twitter:label1":"Estimation du temps de lecture","twitter:data1":"1 minute"},"aioseo_meta_data":{"post_id":"18202","title":"Lame de truelle de finition en plastique 6&quot;x18&quot;x0.500&quot;","description":"D\u00e9couvrez notre lame de truelle Plastique-Pro avec une taille de 6&quot;x18&quot;x0.500&quot; pour une performance optimale lors du lissage du b\u00e9ton.","keywords":null,"keyphrases":null,"primary_term":{"product_cat":0},"canonical_url":"","og_title":"","og_description":"","og_object_type":"default","og_image_type":"featured","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":"","og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":"","twitter_image_custom_fields":null,"twitter_title":"Lame de truelle de finition en plastique 6\"x18\"x0.500\"","twitter_description":"","schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-07-07 22:16:10","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2024-01-22 09:36:22","updated":"2026-07-07 22:16:10"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/plate2000.com\/fr\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/plate2000.com\/fr\/concrete-products\/\" title=\"Produits b\u00e9ton\">Produits b\u00e9ton<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/\" title=\"Lames de truelles\">Lames de truelles<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/plastique-pro\/\" title=\"Plastique Pro \u2013 0.375 I 0.500\">Plastique Pro \u2013 0.375 I 0.500<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/\" title=\"Finition\">Finition<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tTR618500PRP 6\u2033 X 18\u2033 X 0,500\u2033\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/plate2000.com\/fr\/"},{"label":"Produits b\u00e9ton","link":"https:\/\/plate2000.com\/fr\/concrete-products\/"},{"label":"Lames de truelles","link":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/"},{"label":"Plastique Pro \u2013 0.375 I 0.500","link":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/plastique-pro\/"},{"label":"Finition","link":"https:\/\/plate2000.com\/fr\/concrete\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/"},{"label":"TR618500PRP 6&#8243; X 18&#8243; X 0,500&#8243;","link":"https:\/\/plate2000.com\/fr\/product\/lames-de-truelles\/plastique-pro\/finition-plastique-pro\/tr618500prp-6-x-18-x-0500-plastic-finish-blade\/"}],"_links":{"self":[{"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product\/18202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/comments?post=18202"}],"version-history":[{"count":0,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product\/18202\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/media\/18073"}],"wp:attachment":[{"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/media?parent=18202"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product_cat?post=18202"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product_tag?post=18202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}