{"id":18305,"date":"2023-12-18T03:25:51","date_gmt":"2023-12-18T03:25:51","guid":{"rendered":"https:\/\/plate2000.com\/product\/fp48-4s-flat-pan-with-safety-bracket\/"},"modified":"2024-04-24T18:31:37","modified_gmt":"2024-04-24T18:31:37","slug":"fp48-4s-flat-pan-with-safety-bracket","status":"publish","type":"product","link":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp48-4s-flat-pan-with-safety-bracket\/","title":{"rendered":"FP48-4S DISQUE PLAT AVEC ATTACHE \u00c0 GOUPILLE"},"content":{"rendered":"<p>P2K propose une gamme compl\u00e8te de disques pour soutenir divers projets de finition de b\u00e9ton. Trois collections principales : The Rock &#038; The Master, offrant une gamme unique de syst\u00e8mes d&#8217;attaches, et The Roadrunner, qui pr\u00e9sente nos disques \u00e0 bordure. La s\u00e9lection comprend des disques plats, des disques super plats, des disques plats universels et super plats universels, des disques \u00e0 bordures, des flotteurs \u00e0 lames avec clip et des disques \u00e0 blocs soud\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fabriqu\u00e9 en acier de haute qualit\u00e9 de calibre 10 pour une meilleure durabilit\u00e9. Disques plats pour faciliter la direction et le contr\u00f4le de l&#8217;op\u00e9rateur. Les attaches de s\u00e9curit\u00e9 utilisent des goupilles de verrouillage pour fixer la lame de la truelle au disque. Convient aux machines \u00e0 4 lames. Couvre une large surface de contact. Permet d&#8217;obtenir des sols plus plats et d&#8217;augmenter la production. Les goupilles de s\u00e9curit\u00e9 sont vendues s\u00e9par\u00e9ment.<\/p>\n","protected":false},"featured_media":17660,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[134,110,107],"product_tag":[],"class_list":{"0":"post-18305","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-disque-plat-le-magistral","7":"product_cat-le-magistral-attache-a-goupille","8":"product_cat-disques","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product\/18305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/comments?post=18305"}],"version-history":[{"count":0,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product\/18305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/media\/17660"}],"wp:attachment":[{"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/media?parent=18305"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product_cat?post=18305"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product_tag?post=18305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}