{"id":18323,"date":"2023-12-18T03:25:00","date_gmt":"2023-12-18T03:25:00","guid":{"rendered":"https:\/\/plate2000.com\/product\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/"},"modified":"2024-04-24T18:10:15","modified_gmt":"2024-04-24T18:10:15","slug":"fp36-4swb-flat-pan-with-safety-bracket-with-welded-block","status":"publish","type":"product","link":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/","title":{"rendered":"FP36-4SWB DISQUE PLAT AVEC ATTACHE \u00c0 GOUPILLE ET BLOC SOUD\u00c9"},"content":{"rendered":"<p>P2K propose une gamme compl\u00e8te de disques pour soutenir divers projets de finition de b\u00e9ton. Trois collections principales : The Rock &#038; The Master, offrant une gamme unique de syst\u00e8mes d&#8217;attaches, et The Roadrunner, qui pr\u00e9sente nos disques \u00e0 bordure. La s\u00e9lection comprend des disques plats, des disques super plats, des disques plats universels et super plats universels, des disques \u00e0 bordures, des flotteurs \u00e0 lames avec clip et des disques \u00e0 blocs soud\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bloc soud\u00e9 pour un contr\u00f4le plus facile de la direction sur une machine \u00e0 controle arri\u00e8re. Fabriqu\u00e9 en acier de haute qualit\u00e9 de calibre 12 pour une meilleure durabilit\u00e9. Les attaches de s\u00e9curit\u00e9 utilisent des goupilles de verrouillage pour fixer la lame de la truelle au disque. Convient aux machines \u00e0 4 lames. Couvre une large surface de contact. Permet d&#8217;obtenir des sols plus plats et d&#8217;augmenter la production. Les goupilles de s\u00e9curit\u00e9 sont vendues s\u00e9par\u00e9ment.<\/p>\n","protected":false},"featured_media":17586,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[110,134,107],"product_tag":[],"class_list":["post-18323","product","type-product","status-publish","has-post-thumbnail","product_cat-le-magistral-attache-a-goupille","product_cat-disque-plat-le-magistral","product_cat-disques","first","instock","shipping-taxable","product-type-simple"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Le disque plat en b\u00e9ton FP36-4SWB de 36 pouces avec bloc soud\u00e9 assure un polissage sup\u00e9rieur. Ses 4 lames garantissent des finitions impeccables. Optez pour la qualit\u00e9 et l&#039;efficacit\u00e9 sur vos chantiers.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Plate 2000 (P2K)\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"disque pollisage b\u00e9ton Plat 36 pouces 4 lames avec bloc soud\u00e9\" \/>\n\t\t<meta property=\"og:description\" content=\"Le disque plat en b\u00e9ton FP36-4SWB de 36 pouces avec bloc soud\u00e9 assure un polissage sup\u00e9rieur. Ses 4 lames garantissent des finitions impeccables. Optez pour la qualit\u00e9 et l&#039;efficacit\u00e9 sur vos chantiers.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/FP36-4SWB.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/FP36-4SWB.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-12-18T03:25:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-24T18:10:15+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/plate2000\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"disque pollisage b\u00e9ton Plat 36 pouces 4 lames avec bloc soud\u00e9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Le disque plat en b\u00e9ton FP36-4SWB de 36 pouces avec bloc soud\u00e9 assure un polissage sup\u00e9rieur. Ses 4 lames garantissent des finitions impeccables. Optez pour la qualit\u00e9 et l&#039;efficacit\u00e9 sur vos chantiers.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/FP36-4SWB.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete-products\\\/#listItem\",\"name\":\"Produits b\\u00e9ton\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete-products\\\/#listItem\",\"position\":2,\"name\":\"Produits b\\u00e9ton\",\"item\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete-products\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/disques\\\/#listItem\",\"name\":\"Disques\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/disques\\\/#listItem\",\"position\":3,\"name\":\"Disques\",\"item\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/disques\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/disques\\\/le-magistral-attache-a-goupille\\\/#listItem\",\"name\":\"Le Magistral \\u2013 Attache \\u00e0 goupille\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete-products\\\/#listItem\",\"name\":\"Produits b\\u00e9ton\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/disques\\\/le-magistral-attache-a-goupille\\\/#listItem\",\"position\":4,\"name\":\"Le Magistral \\u2013 Attache \\u00e0 goupille\",\"item\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/disques\\\/le-magistral-attache-a-goupille\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/#listItem\",\"name\":\"Disque plat\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/disques\\\/#listItem\",\"name\":\"Disques\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/#listItem\",\"position\":5,\"name\":\"Disque plat\",\"item\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\\\/#listItem\",\"name\":\"FP36-4SWB DISQUE PLAT AVEC ATTACHE \\u00c0 GOUPILLE ET BLOC SOUD\\u00c9\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/disques\\\/le-magistral-attache-a-goupille\\\/#listItem\",\"name\":\"Le Magistral \\u2013 Attache \\u00e0 goupille\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\\\/#listItem\",\"position\":6,\"name\":\"FP36-4SWB DISQUE PLAT AVEC ATTACHE \\u00c0 GOUPILLE ET BLOC SOUD\\u00c9\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/concrete\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/#listItem\",\"name\":\"Disque plat\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/#organization\",\"name\":\"Plate 2000 (P2K)\",\"description\":\"Manufacturer of concrete finishing products with a proven track record for quality and a focus on innovation.\",\"url\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/\",\"telephone\":\"+18778850085\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/plate2000.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/P2K_logo_rvb_noir.png\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\\\/#organizationLogo\",\"width\":976,\"height\":507,\"caption\":\"Black and red logo with letters P2K on gray background\"},\"image\":{\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/plate2000\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\\\/#webpage\",\"url\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\\\/\",\"name\":\"disque pollisage b\\u00e9ton Plat 36 pouces 4 lames avec bloc soud\\u00e9\",\"description\":\"Le disque plat en b\\u00e9ton FP36-4SWB de 36 pouces avec bloc soud\\u00e9 assure un polissage sup\\u00e9rieur. Ses 4 lames garantissent des finitions impeccables. Optez pour la qualit\\u00e9 et l'efficacit\\u00e9 sur vos chantiers.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/plate2000.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/FP36-4SWB.jpg\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\\\/#mainImage\",\"width\":2000,\"height\":2000},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/product\\\/disques\\\/le-magistral-attache-a-goupille\\\/disque-plat-le-magistral\\\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\\\/#mainImage\"},\"datePublished\":\"2023-12-18T03:25:00+00:00\",\"dateModified\":\"2024-04-24T18:10:15+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/\",\"name\":\"Plate 2000 (P2K)\",\"description\":\"Manufacturer of concrete finishing products with a proven track record for quality and a focus on innovation.\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/plate2000.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>disque pollisage b\u00e9ton Plat 36 pouces 4 lames avec bloc soud\u00e9<\/title>\n\n","aioseo_head_json":{"title":"disque pollisage b\u00e9ton Plat 36 pouces 4 lames avec bloc soud\u00e9","description":"Le disque plat en b\u00e9ton FP36-4SWB de 36 pouces avec bloc soud\u00e9 assure un polissage sup\u00e9rieur. Ses 4 lames garantissent des finitions impeccables. Optez pour la qualit\u00e9 et l'efficacit\u00e9 sur vos chantiers.","canonical_url":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/plate2000.com\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete-products\/#listItem","name":"Produits b\u00e9ton"}},{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete-products\/#listItem","position":2,"name":"Produits b\u00e9ton","item":"https:\/\/plate2000.com\/fr\/concrete-products\/","nextItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/disques\/#listItem","name":"Disques"},"previousItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/disques\/#listItem","position":3,"name":"Disques","item":"https:\/\/plate2000.com\/fr\/concrete\/disques\/","nextItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/disques\/le-magistral-attache-a-goupille\/#listItem","name":"Le Magistral \u2013 Attache \u00e0 goupille"},"previousItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete-products\/#listItem","name":"Produits b\u00e9ton"}},{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/disques\/le-magistral-attache-a-goupille\/#listItem","position":4,"name":"Le Magistral \u2013 Attache \u00e0 goupille","item":"https:\/\/plate2000.com\/fr\/concrete\/disques\/le-magistral-attache-a-goupille\/","nextItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/#listItem","name":"Disque plat"},"previousItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/disques\/#listItem","name":"Disques"}},{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/#listItem","position":5,"name":"Disque plat","item":"https:\/\/plate2000.com\/fr\/concrete\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/","nextItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/#listItem","name":"FP36-4SWB DISQUE PLAT AVEC ATTACHE \u00c0 GOUPILLE ET BLOC SOUD\u00c9"},"previousItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/disques\/le-magistral-attache-a-goupille\/#listItem","name":"Le Magistral \u2013 Attache \u00e0 goupille"}},{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/#listItem","position":6,"name":"FP36-4SWB DISQUE PLAT AVEC ATTACHE \u00c0 GOUPILLE ET BLOC SOUD\u00c9","previousItem":{"@type":"ListItem","@id":"https:\/\/plate2000.com\/fr\/concrete\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/#listItem","name":"Disque plat"}}]},{"@type":"Organization","@id":"https:\/\/plate2000.com\/fr\/#organization","name":"Plate 2000 (P2K)","description":"Manufacturer of concrete finishing products with a proven track record for quality and a focus on innovation.","url":"https:\/\/plate2000.com\/fr\/","telephone":"+18778850085","logo":{"@type":"ImageObject","url":"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/P2K_logo_rvb_noir.png","@id":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/#organizationLogo","width":976,"height":507,"caption":"Black and red logo with letters P2K on gray background"},"image":{"@id":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/plate2000"]},{"@type":"WebPage","@id":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/#webpage","url":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/","name":"disque pollisage b\u00e9ton Plat 36 pouces 4 lames avec bloc soud\u00e9","description":"Le disque plat en b\u00e9ton FP36-4SWB de 36 pouces avec bloc soud\u00e9 assure un polissage sup\u00e9rieur. Ses 4 lames garantissent des finitions impeccables. Optez pour la qualit\u00e9 et l'efficacit\u00e9 sur vos chantiers.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/plate2000.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/FP36-4SWB.jpg","@id":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/#mainImage","width":2000,"height":2000},"primaryImageOfPage":{"@id":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/#mainImage"},"datePublished":"2023-12-18T03:25:00+00:00","dateModified":"2024-04-24T18:10:15+00:00"},{"@type":"WebSite","@id":"https:\/\/plate2000.com\/fr\/#website","url":"https:\/\/plate2000.com\/fr\/","name":"Plate 2000 (P2K)","description":"Manufacturer of concrete finishing products with a proven track record for quality and a focus on innovation.","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/plate2000.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Plate 2000 (P2K)","og:type":"article","og:title":"disque pollisage b\u00e9ton Plat 36 pouces 4 lames avec bloc soud\u00e9","og:description":"Le disque plat en b\u00e9ton FP36-4SWB de 36 pouces avec bloc soud\u00e9 assure un polissage sup\u00e9rieur. Ses 4 lames garantissent des finitions impeccables. Optez pour la qualit\u00e9 et l'efficacit\u00e9 sur vos chantiers.","og:url":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/","og:image":"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/FP36-4SWB.jpg","og:image:secure_url":"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/FP36-4SWB.jpg","og:image:width":2000,"og:image:height":2000,"article:published_time":"2023-12-18T03:25:00+00:00","article:modified_time":"2024-04-24T18:10:15+00:00","article:publisher":"https:\/\/www.facebook.com\/plate2000","twitter:card":"summary_large_image","twitter:title":"disque pollisage b\u00e9ton Plat 36 pouces 4 lames avec bloc soud\u00e9","twitter:description":"Le disque plat en b\u00e9ton FP36-4SWB de 36 pouces avec bloc soud\u00e9 assure un polissage sup\u00e9rieur. Ses 4 lames garantissent des finitions impeccables. Optez pour la qualit\u00e9 et l'efficacit\u00e9 sur vos chantiers.","twitter:image":"https:\/\/plate2000.com\/wp-content\/uploads\/2023\/12\/FP36-4SWB.jpg"},"aioseo_meta_data":{"post_id":"18323","title":"disque pollisage b\u00e9ton Plat 36 pouces 4 lames avec bloc soud\u00e9","description":"Le disque plat en b\u00e9ton FP36-4SWB de 36 pouces avec bloc soud\u00e9 assure un polissage sup\u00e9rieur. Ses 4 lames garantissent des finitions impeccables. Optez pour la qualit\u00e9 et l&#039;efficacit\u00e9 sur vos chantiers.","keywords":null,"keyphrases":null,"primary_term":{"product_cat":0},"canonical_url":"","og_title":"","og_description":"","og_object_type":"default","og_image_type":"featured","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":"","og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":"","twitter_image_custom_fields":null,"twitter_title":"disque pollisage b\u00e9ton Plat 36 pouces 4 lames avec bloc soud\u00e9","twitter_description":"","schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-07-07 23:49:26","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2024-01-22 09:12:09","updated":"2026-07-07 23:49:26"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/plate2000.com\/fr\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/plate2000.com\/fr\/concrete-products\/\" title=\"Produits b\u00e9ton\">Produits b\u00e9ton<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/plate2000.com\/fr\/concrete\/disques\/\" title=\"Disques\">Disques<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/plate2000.com\/fr\/concrete\/disques\/le-magistral-attache-a-goupille\/\" title=\"Le Magistral \u2013 Attache \u00e0 goupille\">Le Magistral \u2013 Attache \u00e0 goupille<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/plate2000.com\/fr\/concrete\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/\" title=\"Disque plat\">Disque plat<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tFP36-4SWB DISQUE PLAT AVEC ATTACHE \u00c0 GOUPILLE ET BLOC SOUD\u00c9\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/plate2000.com\/fr\/"},{"label":"Produits b\u00e9ton","link":"https:\/\/plate2000.com\/fr\/concrete-products\/"},{"label":"Disques","link":"https:\/\/plate2000.com\/fr\/concrete\/disques\/"},{"label":"Le Magistral \u2013 Attache \u00e0 goupille","link":"https:\/\/plate2000.com\/fr\/concrete\/disques\/le-magistral-attache-a-goupille\/"},{"label":"Disque plat","link":"https:\/\/plate2000.com\/fr\/concrete\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/"},{"label":"FP36-4SWB DISQUE PLAT AVEC ATTACHE \u00c0 GOUPILLE ET BLOC SOUD\u00c9","link":"https:\/\/plate2000.com\/fr\/product\/disques\/le-magistral-attache-a-goupille\/disque-plat-le-magistral\/fp36-4swb-flat-pan-with-safety-bracket-with-welded-block\/"}],"_links":{"self":[{"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product\/18323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/comments?post=18323"}],"version-history":[{"count":0,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product\/18323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/media\/17586"}],"wp:attachment":[{"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/media?parent=18323"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product_cat?post=18323"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/plate2000.com\/fr\/wp-json\/wp\/v2\/product_tag?post=18323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}